{"id":13533,"date":"2024-09-23T13:47:01","date_gmt":"2024-09-23T13:47:01","guid":{"rendered":"https:\/\/new-www.sii.pl\/branch\/wroclaw\/"},"modified":"2026-03-31T09:27:42","modified_gmt":"2026-03-31T09:27:42","slug":"wroclaw","status":"publish","type":"branch","link":"https:\/\/sii.pl\/de\/buros\/wroclaw\/","title":{"rendered":"Wroc\u0142aw"},"content":{"rendered":"\n<section class=\"wp-block-nsw-block-section nsw-section  section-ce7bf5ac-6c42-478f-b237-bf1fa6f8b2d2\" id=\"\"><style type=\"text\/css\">.section-ce7bf5ac-6c42-478f-b237-bf1fa6f8b2d2 { padding-top:120px;padding-bottom:120px;background:#ffffff; }\n     \t\t\t\t\t @media screen and (max-width: 991px) { .section-ce7bf5ac-6c42-478f-b237-bf1fa6f8b2d2 { padding-top:48px;padding-bottom:48px; } }<\/style>\n<div class=\"wp-block-sii-nsw-header container\"><style type=\"text\/css\">.header-7f66553e-0262-43ee-903c-fbc2f4f39d17 .nsw-m-title-block__title, .header-7f66553e-0262-43ee-903c-fbc2f4f39d17 .nsw-m-title-block__subtitle {  }\n                         @media screen and (max-width: 991px) { .header-7f66553e-0262-43ee-903c-fbc2f4f39d17 .nsw-m-title-block__title, .header-7f66553e-0262-43ee-903c-fbc2f4f39d17 .nsw-m-title-block__subtitle {  } }<\/style><header class=\"nsw-header nsw-m-title-block  header-7f66553e-0262-43ee-903c-fbc2f4f39d17 -h2 -uppercase -p1 -at0\"><span class=\"nsw-m-title-block__above-title \"><\/span><h2 class=\"nsw-m-title-block__title \"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-nswc-gradient-color\">14 B\u00fcros<\/mark>&nbsp;in den gr\u00f6\u00dften polnischen St\u00e4dten<\/h2><p class=\"nsw-m-title-block__subtitle \">W\u00e4hle deinen Standort, um mehr Informationen zu erhalten<\/p><\/header><\/div>\n\n\n\n<div class=\"wp-block-sii-nsw-container container container-a2833333-0ebc-4c08-aa12-a2fb5d8abceb\"><style type=\"text\/css\">.container-a2833333-0ebc-4c08-aa12-a2fb5d8abceb { margin-top:40px; }\n                         @media screen and (max-width: 991px) { .container-a2833333-0ebc-4c08-aa12-a2fb5d8abceb { margin-top:16px; } }<\/style><div class=\"nsw-o-branches-tabs \">\n    \n    <div class=\"nsw-o-branches-tabs__container u-hidden-on-mobile\">\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/bialystok\/\" class=\"nsw-o-branches-tabs__btn \">\n                    <span>Bia\u0142ystok<\/span>\n                <\/a>\n            <\/div>\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/bydgoszcz\/\" class=\"nsw-o-branches-tabs__btn \">\n                    <span>Bydgoszcz<\/span>\n                <\/a>\n            <\/div>\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/gdansk\/\" class=\"nsw-o-branches-tabs__btn \">\n                    <span>Gda\u0144sk<\/span>\n                <\/a>\n            <\/div>\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/katowice\/\" class=\"nsw-o-branches-tabs__btn \">\n                    <span>Katowice<\/span>\n                <\/a>\n            <\/div>\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/krakow\/\" class=\"nsw-o-branches-tabs__btn \">\n                    <span>Krak\u00f3w<\/span>\n                <\/a>\n            <\/div>\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/lublin\/\" class=\"nsw-o-branches-tabs__btn \">\n                    <span>Lublin<\/span>\n                <\/a>\n            <\/div>\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/lodz\/\" class=\"nsw-o-branches-tabs__btn \">\n                    <span>\u0141\u00f3d\u017a<\/span>\n                <\/a>\n            <\/div>\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/pila\/\" class=\"nsw-o-branches-tabs__btn \">\n                    <span>Pi\u0142a<\/span>\n                <\/a>\n            <\/div>\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/poznan\/\" class=\"nsw-o-branches-tabs__btn \">\n                    <span>Pozna\u0144<\/span>\n                <\/a>\n            <\/div>\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/rzeszow\/\" class=\"nsw-o-branches-tabs__btn \">\n                    <span>Rzesz\u00f3w<\/span>\n                <\/a>\n            <\/div>\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/szczecin\/\" class=\"nsw-o-branches-tabs__btn \">\n                    <span>Szczecin<\/span>\n                <\/a>\n            <\/div>\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/torun\/\" class=\"nsw-o-branches-tabs__btn \">\n                    <span>Toru\u0144<\/span>\n                <\/a>\n            <\/div>\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/warszawa\/\" class=\"nsw-o-branches-tabs__btn \">\n                    <span>Warszawa<\/span>\n                <\/a>\n            <\/div>\n                    \n            <div class=\"nsw-o-branches-tabs__tab\">\n                <a href=\"https:\/\/sii.pl\/de\/buros\/wroclaw\/\" class=\"nsw-o-branches-tabs__btn -active\">\n                    <span>Wroc\u0142aw<\/span>\n                <\/a>\n            <\/div>\n            <\/div>\n\n    <div class=\"nsw-o-branches-tabs__mobile u-hidden-on-desktop\">\n        <div class=\"nsw-o-branches-tabs__dropdown nsw-m-filter-dropdown js-dropdown-filter\">\n            <a href=\"#\" class=\"nsw-m-filter-dropdown__filter-btn d-flex flex-row align-items-center justify-content-between js-dropDown-button\" rel=\"nofollow\" >\n                <span class=\"nsw-o-branches-tabs__dropdown-title u-text-truncate\">Wroc\u0142aw<\/span>\n                <span class=\"nsw-m-filter-dropdown__filter-btn-icon\">  <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 32 32\" id=\"angle-down\">\n    <title>angle-down<\/title>\n    <path d=\"M4.219 10.781L16 22.562l11.781-11.781 1.438 1.438-12.5 12.5-.719.688-.719-.688-12.5-12.5z\"><\/path>\n  <\/svg><\/span>\n            <\/a>\n            <div class=\"nsw-m-filter-dropdown__hoverContent\">\n                <div class=\"nsw-m-filter-dropdown__hoverContent-inner\">\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/bialystok\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between \">\n                            <span>Bia\u0142ystok<\/span>\n                        <\/a>\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/bydgoszcz\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between \">\n                            <span>Bydgoszcz<\/span>\n                        <\/a>\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/gdansk\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between \">\n                            <span>Gda\u0144sk<\/span>\n                        <\/a>\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/katowice\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between \">\n                            <span>Katowice<\/span>\n                        <\/a>\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/krakow\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between \">\n                            <span>Krak\u00f3w<\/span>\n                        <\/a>\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/lublin\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between \">\n                            <span>Lublin<\/span>\n                        <\/a>\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/lodz\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between \">\n                            <span>\u0141\u00f3d\u017a<\/span>\n                        <\/a>\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/pila\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between \">\n                            <span>Pi\u0142a<\/span>\n                        <\/a>\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/poznan\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between \">\n                            <span>Pozna\u0144<\/span>\n                        <\/a>\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/rzeszow\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between \">\n                            <span>Rzesz\u00f3w<\/span>\n                        <\/a>\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/szczecin\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between \">\n                            <span>Szczecin<\/span>\n                        <\/a>\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/torun\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between \">\n                            <span>Toru\u0144<\/span>\n                        <\/a>\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/warszawa\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between \">\n                            <span>Warszawa<\/span>\n                        <\/a>\n                                                                    <a href=\"https:\/\/sii.pl\/de\/buros\/wroclaw\/\" class=\"nsw-o-branches-tabs__option nsw-m-filter-dropdown__row d-flex flex-row justify-content-between -active\">\n                            <span>Wroc\u0142aw<\/span>\n                        <\/a>\n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-nsw-block-section nsw-section  section-5847b06b-39c7-441a-affa-ab5925a5d94e\" id=\"\"><style type=\"text\/css\">.section-5847b06b-39c7-441a-affa-ab5925a5d94e { padding-top:120px;padding-bottom:60px;background:#F5F9FE; }\n     \t\t\t\t\t @media screen and (max-width: 991px) { .section-5847b06b-39c7-441a-affa-ab5925a5d94e { padding-top:60px;padding-bottom:4px; } }<\/style>\n<div class=\"wp-block-sii-nsw-header container\"><style type=\"text\/css\">.header-561f809d-f9de-4a3f-b70a-234c800be8d6 .nsw-m-title-block__title, .header-561f809d-f9de-4a3f-b70a-234c800be8d6 .nsw-m-title-block__subtitle {  }\n                         @media screen and (max-width: 991px) { .header-561f809d-f9de-4a3f-b70a-234c800be8d6 .nsw-m-title-block__title, .header-561f809d-f9de-4a3f-b70a-234c800be8d6 .nsw-m-title-block__subtitle {  } }<\/style><header class=\"nsw-header nsw-m-title-block  header-561f809d-f9de-4a3f-b70a-234c800be8d6 -h2 -p1 -at0\"><span class=\"nsw-m-title-block__above-title \"><\/span><h2 class=\"nsw-m-title-block__title \">WILKOMMEN IN <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-nswc-gradient-color\">WROC\u0141AW!<\/mark><\/h2><p class=\"nsw-m-title-block__subtitle \">Wir sind Spezialisten auf dem Gebiet der Technologien: Java, .Net, BI und Tests, indem wir Projekte f\u00fcr Automobilindustrie, Bankwesen und Telekommunikation umsetzen.<\/p><\/header><\/div>\n\n\n\n<div class=\"wp-block-sii-nsw-container container container-df7082eb-3b35-444f-b3a5-33fded48e6c1\"><style type=\"text\/css\">.container-df7082eb-3b35-444f-b3a5-33fded48e6c1 { margin-top:64px; }\n                         @media screen and (max-width: 991px) { .container-df7082eb-3b35-444f-b3a5-33fded48e6c1 { margin-top:24px; } }<\/style>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:80%\"><div class=\"nsw-o-info-boxes d-flex justify-content-between flex-column flex-xl-row -mobile-smaller-margin\">\n            <div class=\"nsw-o-info-box\">\n                    <div class=\"nsw-m-title-block -h1 -p4 -has-title-margin-bottom-0 -has-subtitle-color-default -has-title-mark-color-gradient-main -has-subtitle-mark-color-gradient-main\">\n                                <h2 class=\"nsw-m-title-block__title\"><mark>2009<\/mark><\/h2>\n                        <p class=\"nsw-m-title-block__subtitle\">Er\u00f6ffnungsdatum<\/p>\n    <\/div>\n                                        <\/div>\n            <div class=\"nsw-o-info-box\">\n                    <div class=\"nsw-m-title-block -h1 -p4 -has-title-margin-bottom-0 -has-subtitle-color-default -has-title-mark-color-gradient-main -has-subtitle-mark-color-gradient-main\">\n                                <h2 class=\"nsw-m-title-block__title\"><mark>2 259<\/mark><\/h2>\n                        <p class=\"nsw-m-title-block__subtitle\">m<sup>2<\/sup> B\u00fcrofl\u00e4che<\/p>\n    <\/div>\n                                        <\/div>\n            <div class=\"nsw-o-info-box\">\n                    <div class=\"nsw-m-title-block -h1 -p4 -has-title-margin-bottom-0 -has-subtitle-color-default -has-title-mark-color-gradient-main -has-subtitle-mark-color-gradient-main\">\n                                <h2 class=\"nsw-m-title-block__title\"><mark>908<\/mark><\/h2>\n                        <p class=\"nsw-m-title-block__subtitle\">Power People<\/p>\n    <\/div>\n                                        <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><\/div>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-nsw-block-section nsw-section  section-b24e238f-e2f3-41a9-aa67-ecb7a36a383b\" id=\"\"><style type=\"text\/css\">.section-b24e238f-e2f3-41a9-aa67-ecb7a36a383b { padding-top:60px;padding-bottom:80px;background:#F5F9FE; }\n     \t\t\t\t\t @media screen and (max-width: 991px) { .section-b24e238f-e2f3-41a9-aa67-ecb7a36a383b { padding-top:32px;padding-bottom:40px; } }<\/style>\n<div class=\"wp-block-sii-nsw-header container\"><style type=\"text\/css\">.header-12221f4d-ada9-40e7-905b-4d45111649e0 .nsw-m-title-block__title, .header-12221f4d-ada9-40e7-905b-4d45111649e0 .nsw-m-title-block__subtitle {  }\n                         @media screen and (max-width: 991px) { .header-12221f4d-ada9-40e7-905b-4d45111649e0 .nsw-m-title-block__title, .header-12221f4d-ada9-40e7-905b-4d45111649e0 .nsw-m-title-block__subtitle {  } }<\/style><header class=\"nsw-header nsw-m-title-block  header-12221f4d-ada9-40e7-905b-4d45111649e0 -h2 -uppercase -t2 -at0\"><span class=\"nsw-m-title-block__above-title \"><\/span><h2 class=\"nsw-m-title-block__title \">Unser&nbsp;<mark><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-nswc-gradient-color\">Standort<\/mark><\/mark><\/h2><p class=\"nsw-m-title-block__subtitle \"><\/p><\/header><\/div>\n\n\n\n<div class=\"wp-block-sii-nsw-container container container-b3b733d6-379c-470b-8824-8bf82ea97415\"><style type=\"text\/css\">.container-b3b733d6-379c-470b-8824-8bf82ea97415 { margin-top:40px; }\n                         @media screen and (max-width: 991px) { .container-b3b733d6-379c-470b-8824-8bf82ea97415 { margin-top:24px; } }<\/style><div class=\"nsw-m-branch-contact\">\n            <div class=\"nsw-m-branch-contact__container d-flex flex-column flex-md-row\">\n                <div class=\"nsw-m-branch-contact__icon u-mobile-bottom-positive-8\">\n                    <svg width=\"13\" height=\"13\" viewBox=\"0 0 13 13\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M6.5 0C3.97993 0 1.92969 2.05024 1.92969 4.57031C1.92969 5.42176 2.16554 6.2527 2.61191 6.97359L6.23985 12.82C6.30934 12.932 6.43178 13 6.56345 13C6.56447 13 6.56546 13 6.56647 13C6.69929 12.999 6.82198 12.9288 6.8902 12.8149L10.4257 6.91184C10.8474 6.20618 11.0703 5.3965 11.0703 4.57031C11.0703 2.05024 9.02007 0 6.5 0ZM9.77199 6.52077L6.55769 11.8875L3.25932 6.57226C2.88778 5.97223 2.68633 5.27998 2.68633 4.57031C2.68633 2.47025 4.39994 0.756641 6.5 0.756641C8.60006 0.756641 10.3111 2.47025 10.3111 4.57031C10.3111 5.25893 10.123 5.93348 9.77199 6.52077Z\"\/>\n<path d=\"M6.5 2.28516C5.23996 2.28516 4.21484 3.31028 4.21484 4.57031C4.21484 5.8223 5.22328 6.85547 6.5 6.85547C7.79246 6.85547 8.78516 5.80854 8.78516 4.57031C8.78516 3.31028 7.76004 2.28516 6.5 2.28516ZM6.5 6.09883C5.65558 6.09883 4.97148 5.41244 4.97148 4.57031C4.97148 3.73029 5.65998 3.0418 6.5 3.0418C7.34002 3.0418 8.02598 3.73029 8.02598 4.57031C8.02598 5.40015 7.3578 6.09883 6.5 6.09883Z\"\/>\n<\/svg>\n\n                <\/div>\n                <div class=\"nsw-m-branch-contact__content\">\n                    <p class=\"has-nsw-p-2-font-size u-color-nswc-grey-1000 -u-bottom-positive-16 u-mobile-bottom-positive-8\">\n                        ul. Na Ostatnim Groszu 3\n                        <br>\n                                                54-207 Wroc\u0142aw\n                                            <\/p>\n                                            <a  href=\"https:\/\/www.google.com\/maps\/place\/Na+Ostatnim+Groszu+3,+Wroc%C5%82aw\/@51.1249883,16.9754537,17z\/data=!3m1!4b1!4m5!3m4!1s0x470fea0b8148809d:0xfab5fc2bd44b9e0!8m2!3d51.124985!4d16.9776424\" class=\"nsw-a-button -link -icon-small -icon-right\"    rel=\"nofollow\" >\n        <span>Ansicht auf Karte<\/span>\n            <span class=\"nsw-a-button__icon\">\n               <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 32 32\" id=\"angle-right\">\n    <title>angle-right<\/title>\n    <path d=\"M12.969 4.281l11 11 .688.719-.688.719-11 11-1.438-1.438L21.812 16 11.531 5.719z\"><\/path>\n  <\/svg>\n         <\/span>\n    <\/a>\n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-nsw-block-section nsw-section  section-298045d8-9b63-43b0-b3e0-b77ac8c8dc04\" id=\"\"><style type=\"text\/css\">.section-298045d8-9b63-43b0-b3e0-b77ac8c8dc04 { padding-top:0px;padding-bottom:80px;background:linear-gradient(0deg, rgba(245, 249, 254, 0) 35.51%, rgba(245, 249, 254, 0.48) 55.73%, rgba(245, 249, 254, 1) 78.08%); }\n     \t\t\t\t\t @media screen and (max-width: 991px) { .section-298045d8-9b63-43b0-b3e0-b77ac8c8dc04 { padding-top:0px;padding-bottom:64px; } }<\/style>\n<div class=\"wp-block-sii-nsw-container container container-67fa140c-d7a7-48b9-9d00-e3466a46637d\"><style type=\"text\/css\">.container-67fa140c-d7a7-48b9-9d00-e3466a46637d {  }\n                         @media screen and (max-width: 991px) { .container-67fa140c-d7a7-48b9-9d00-e3466a46637d {  } }<\/style><div class=\"sii-o-panel-horizontal-map  -nsw-mod\">\n      <div class=\"sii-m-accordion js-accordion sii-o-panel-horizontal-map__accordion js-oneOpen\">\n                  <div class=\"sii-m-accordion__item js-accordion-item active\">\n              <button class=\"sii-m-accordion__header js-accordion-header\">\n                  <div class=\"sii-m-accordion__header__icon\">\n                      <svg width=\"24\" height=\"19\" viewBox=\"0 0 24 19\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M20.4185 2.5533H15.7109V2.42493C15.7109 1.09122 14.6476 0 13.3326 0H10.6604C9.35238 0 8.28213 1.08408 8.28213 2.42493V2.5533H3.57447C1.60886 2.5533 0 4.13664 0 6.09084V19H24V6.09084C24 4.14377 22.3911 2.56044 20.4185 2.56044V2.5533ZM9.68814 2.43206C9.68814 1.88288 10.1288 1.43356 10.6674 1.43356H13.3396C13.8782 1.43356 14.3189 1.88288 14.3189 2.43206V2.54617H9.69513V2.43206H9.68814ZM22.636 17.6021H1.37103V6.09084C1.37103 4.91404 2.36433 3.9512 3.58146 3.9512H8.28913V3.96547H15.7109V3.9512H20.4185C21.6357 3.9512 22.629 4.90691 22.629 6.09084V17.6021H22.636Z\" \/>\n<path d=\"M15.78 10.3512H12.72V7.5088C12.72 7.14096 12.396 6.84 12 6.84C11.604 6.84 11.28 7.14096 11.28 7.5088V10.3512H8.22C7.824 10.3512 7.5 10.6522 7.5 11.02C7.5 11.3878 7.824 11.6888 8.22 11.6888H11.28V14.5312C11.28 14.899 11.604 15.2 12 15.2C12.396 15.2 12.72 14.899 12.72 14.5312V11.6888H15.78C16.176 11.6888 16.5 11.3878 16.5 11.02C16.5 10.6522 16.176 10.3512 15.78 10.3512Z\" \/>\n\n<\/svg>\n\n                  <\/div>\n                  <div class=\"sii-m-accordion__header__text\">\n                      Annehmlichkeiten \n                  <\/div>\n                  <div class=\"sii-m-accordion__header__arrow\">\n                      <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewBox=\"0 0 12 7\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Sites\">\n    <g id=\"Sites-_-Gdansk\" data-name=\"Sites-&amp;gt;-Gdansk\">\n      <polygon id=\"Path-Copy-3\" class=\"cls-1\" points=\"1.4 0 6 4.3 10.6 0 12 1.3 6 7 0 1.3 1.4 0\"\/>\n    <\/g>\n  <\/g>\n<\/svg>\n                  <\/div>\n              <\/button>\n              <div class=\"sii-m-accordion__body js-accordion-body\">\n                  <div class=\"sii-m-accordion__body__contents\">\n                    <ul>\n<li>Medicover-Filiale 650 Meter vom B\u00fcro entfernt<\/li>\n<li>2 km zum Breslauer Markt<\/li>\n<li>Fitnessstudio und Sauna im Sky-Tower-Geb\u00e4ude<\/li>\n<\/ul>\n\n                  <\/div>\n              <\/div>\n          <\/div>\n                  <div class=\"sii-m-accordion__item js-accordion-item \">\n              <button class=\"sii-m-accordion__header js-accordion-header\">\n                  <div class=\"sii-m-accordion__header__icon\">\n                      <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"  xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M0.5 6.84058C0.5 9.21377 2.3095 11.1703 4.63079 11.442V14.413H2.01097C1.70634 14.413 1.46263 14.6546 1.46263 14.9565C1.46263 15.2585 1.70634 15.5 2.01097 15.5H8.34728C8.65191 15.5 8.89561 15.2585 8.89561 14.9565C8.89561 14.6546 8.65191 14.413 8.34728 14.413H5.72746V11.442C8.04874 11.1703 9.85824 9.21377 9.85824 6.84058V0.5H0.5V6.84058ZM1.59667 1.58696H8.76158V6.84058C8.76158 8.7971 7.15313 10.3913 5.17912 10.3913C3.20512 10.3913 1.59667 8.7971 1.59667 6.84058V1.58696Z\" \/>\n<path d=\"M14.9517 0.5C14.647 0.5 14.4033 0.741546 14.4033 1.04348V5.20411C14.4033 6.38768 13.4346 7.34783 12.2405 7.34783H11.6921V14.9565C11.6921 15.2585 11.9358 15.5 12.2405 15.5C12.5451 15.5 12.7888 15.2585 12.7888 14.9565V8.38647C14.3241 8.12681 15.5 6.79831 15.5 5.19807V1.04348C15.5 0.741546 15.2563 0.5 14.9517 0.5Z\"\/>\n<path d=\"M12.2405 5.3128C12.5451 5.3128 12.7888 5.07126 12.7888 4.76932V1.04348C12.7888 0.741546 12.5451 0.5 12.2405 0.5C11.9358 0.5 11.6921 0.741546 11.6921 1.04348V4.76932C11.6921 5.07126 11.9358 5.3128 12.2405 5.3128Z\"\/>\n<\/svg>\n\n                  <\/div>\n                  <div class=\"sii-m-accordion__header__text\">\n                      Gastronomie\n                  <\/div>\n                  <div class=\"sii-m-accordion__header__arrow\">\n                      <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewBox=\"0 0 12 7\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Sites\">\n    <g id=\"Sites-_-Gdansk\" data-name=\"Sites-&amp;gt;-Gdansk\">\n      <polygon id=\"Path-Copy-3\" class=\"cls-1\" points=\"1.4 0 6 4.3 10.6 0 12 1.3 6 7 0 1.3 1.4 0\"\/>\n    <\/g>\n  <\/g>\n<\/svg>\n                  <\/div>\n              <\/button>\n              <div class=\"sii-m-accordion__body js-accordion-body\">\n                  <div class=\"sii-m-accordion__body__contents\">\n                    <ul>\n<li>10 Gastst\u00e4tten in Sky Tower<\/li>\n<li>Viele Restaurants und Bars in der Nachbarschaft<\/li>\n<li>Promenade entlang des Flussufers \u2013 das Gebiet voller Pubs und klimatischer Kneipen<\/li>\n<\/ul>\n\n                  <\/div>\n              <\/div>\n          <\/div>\n                  <div class=\"sii-m-accordion__item js-accordion-item \">\n              <button class=\"sii-m-accordion__header js-accordion-header\">\n                  <div class=\"sii-m-accordion__header__icon\">\n                      <svg width=\"24\" height=\"15\" viewBox=\"0 0 24 15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M19.6938 4.95999H18.785L17.2817 2.75933C16.2071 1.18742 14.4294 0.25 12.526 0.25H9.03349C7.13006 0.25 5.35238 1.18742 4.27777 2.75933L2.67158 5.1086C1.00822 5.73736 -0.0949707 7.3207 -0.0949707 9.10981V10.2759C-0.0949707 11.3105 0.745282 12.145 1.77416 12.145H2.22001C2.42579 13.4768 3.56899 14.5 4.95226 14.5C6.33553 14.5 7.47873 13.4768 7.68451 12.145H10.714C10.9998 12.145 11.2284 11.9164 11.2284 11.6306C11.2284 11.3448 10.9998 11.1161 10.714 11.1161H7.65593C7.37585 9.87575 6.27266 8.94404 4.95226 8.94404C3.63186 8.94404 2.52296 9.87575 2.24859 11.1161H1.77988C1.31688 11.1161 0.93391 10.7389 0.93391 10.2702V9.10409C0.93391 7.70367 1.82561 6.4633 3.15744 6.02316L3.3232 5.966L5.12374 3.33664C6.00401 2.04483 7.4673 1.27888 9.02777 1.27888H12.5203C14.0807 1.27888 15.544 2.05054 16.4243 3.33664L18.2363 5.98315H19.6881C21.5515 5.98315 23.0663 7.49789 23.0663 9.36131V11.1104H21.8259C21.5458 9.87004 20.4426 8.93833 19.1222 8.93833C17.8018 8.93833 16.6929 9.87004 16.4186 11.1104H12.9947C12.7089 11.1104 12.4802 11.339 12.4802 11.6248C12.4802 11.9106 12.7089 12.1393 12.9947 12.1393H16.39C16.5958 13.4711 17.739 14.4943 19.1222 14.4943C20.5055 14.4943 21.6487 13.4711 21.8545 12.1393H23.1292C23.6607 12.1393 24.0952 11.7049 24.0952 11.1733V9.36131C24.0952 6.93201 22.1174 4.95427 19.6881 4.95427L19.6938 4.95999ZM4.95226 9.97292C5.91827 9.97292 6.70136 10.756 6.70136 11.722C6.70136 12.688 5.91827 13.4711 4.95226 13.4711C3.98626 13.4711 3.20316 12.688 3.20316 11.722C3.20316 10.756 3.98626 9.97292 4.95226 9.97292ZM19.128 13.4711C18.1619 13.4711 17.3789 12.688 17.3789 11.722C17.3789 10.756 18.1619 9.97292 19.128 9.97292C20.094 9.97292 20.877 10.756 20.877 11.722C20.877 12.688 20.094 13.4711 19.128 13.4711Z\" \/>\n<path d=\"M15.8813 5.34296C15.8813 5.05716 15.6526 4.82852 15.3668 4.82852H6.68993C6.40413 4.82852 6.17549 5.05716 6.17549 5.34296C6.17549 5.62876 6.40413 5.8574 6.68993 5.8574H15.3668C15.6526 5.8574 15.8813 5.62876 15.8813 5.34296Z\" \/>\n<\/svg>\n\n                  <\/div>\n                  <div class=\"sii-m-accordion__header__text\">\n                      F\u00fcr Autofahrer\n                  <\/div>\n                  <div class=\"sii-m-accordion__header__arrow\">\n                      <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewBox=\"0 0 12 7\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Sites\">\n    <g id=\"Sites-_-Gdansk\" data-name=\"Sites-&amp;gt;-Gdansk\">\n      <polygon id=\"Path-Copy-3\" class=\"cls-1\" points=\"1.4 0 6 4.3 10.6 0 12 1.3 6 7 0 1.3 1.4 0\"\/>\n    <\/g>\n  <\/g>\n<\/svg>\n                  <\/div>\n              <\/button>\n              <div class=\"sii-m-accordion__body js-accordion-body\">\n                  <div class=\"sii-m-accordion__body__contents\">\n                    <ul>\n<li>Tiefgarage im Sky-Tower-Geb\u00e4ude<\/li>\n<\/ul>\n\n                  <\/div>\n              <\/div>\n          <\/div>\n                  <div class=\"sii-m-accordion__item js-accordion-item \">\n              <button class=\"sii-m-accordion__header js-accordion-header\">\n                  <div class=\"sii-m-accordion__header__icon\">\n                      <svg width=\"16\" height=\"14\" viewBox=\"0 0 16 14\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M14.0983 1.94702H13.6281C13.3931 0.978848 12.5184 0.25 11.4688 0.25H4.53683C3.49266 0.25 2.61797 0.973409 2.37743 1.94702H1.90729C1.15833 1.94702 0.551514 2.55077 0.551514 3.29593V6.09166C0.551514 6.36362 0.770186 6.58119 1.04353 6.58119C1.31687 6.58119 1.53554 6.36362 1.53554 6.09166V3.29593C1.53554 3.08924 1.70501 2.92063 1.91275 2.92063H2.3173V12.4011C2.3173 13.1463 2.92411 13.75 3.67307 13.75H4.53683C5.28578 13.75 5.8926 13.1463 5.8926 12.4011V12.1998H10.1075V12.4011C10.1075 13.1463 10.7143 13.75 11.4633 13.75H12.327C13.076 13.75 13.6828 13.1463 13.6828 12.4011V2.92607H14.0874C14.2951 2.92607 14.4646 3.09468 14.4646 3.30137V6.0971C14.4646 6.36906 14.6832 6.58662 14.9566 6.58662C15.2299 6.58662 15.4486 6.36906 15.4486 6.0971V3.30137C15.4486 2.55621 14.8418 1.95246 14.0928 1.95246L14.0983 1.94702ZM4.53683 11.2262C3.85347 11.2262 3.29586 10.6714 3.29586 9.99154V8.57192C3.51453 8.71334 3.76054 8.78405 4.02841 8.78405H11.9772C12.245 8.78405 12.4965 8.7079 12.7097 8.57192V9.99154C12.7097 10.6714 12.1521 11.2262 11.4688 11.2262H4.53683ZM4.53683 1.22905H11.4688C12.1521 1.22905 12.7097 1.78384 12.7097 2.46374V7.23388L12.2396 7.70165C12.163 7.7778 12.081 7.81044 11.9717 7.81044H4.02841C3.91908 7.81044 3.84254 7.7778 3.766 7.70165L3.29586 7.23388V2.46374C3.29586 1.78384 3.85347 1.22905 4.53683 1.22905ZM4.91404 12.4065C4.91404 12.6132 4.74457 12.7818 4.54229 12.7818H3.67854C3.4708 12.7818 3.30132 12.6132 3.30132 12.4065V11.83C3.65667 12.0693 4.08308 12.2053 4.54229 12.2053H4.91404V12.4065ZM12.338 12.7764H11.4742C11.2665 12.7764 11.1025 12.6078 11.1025 12.4011V12.1998H11.4742C11.9334 12.1998 12.3598 12.0584 12.7152 11.8245V12.4011C12.7152 12.6078 12.5457 12.7764 12.338 12.7764Z\" \/>\n<path d=\"M5.10538 9.57273C4.86484 9.57273 4.6735 9.76854 4.6735 10.0024C4.6735 10.2363 4.8703 10.4321 5.10538 10.4321C5.34045 10.4321 5.53725 10.2363 5.53725 10.0024C5.53725 9.76854 5.34045 9.57273 5.10538 9.57273Z\" \/>\n<path d=\"M10.9002 9.57273C10.6597 9.57273 10.4683 9.76854 10.4683 10.0024C10.4683 10.2363 10.6651 10.4321 10.9002 10.4321C11.1353 10.4321 11.3321 10.2363 11.3321 10.0024C11.3321 9.76854 11.1353 9.57273 10.9002 9.57273Z\" \/>\n<path d=\"M9.37496 9.51833H6.63609C6.36274 9.51833 6.14407 9.7359 6.14407 10.0079C6.14407 10.2798 6.36274 10.4974 6.63609 10.4974H9.37496C9.6483 10.4974 9.86698 10.2798 9.86698 10.0079C9.86698 9.7359 9.6483 9.51833 9.37496 9.51833Z\" \/>\n\n<\/svg>\n\n                  <\/div>\n                  <div class=\"sii-m-accordion__header__text\">\n                      Stadtverkehr\n                  <\/div>\n                  <div class=\"sii-m-accordion__header__arrow\">\n                      <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewBox=\"0 0 12 7\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Sites\">\n    <g id=\"Sites-_-Gdansk\" data-name=\"Sites-&amp;gt;-Gdansk\">\n      <polygon id=\"Path-Copy-3\" class=\"cls-1\" points=\"1.4 0 6 4.3 10.6 0 12 1.3 6 7 0 1.3 1.4 0\"\/>\n    <\/g>\n  <\/g>\n<\/svg>\n                  <\/div>\n              <\/button>\n              <div class=\"sii-m-accordion__body js-accordion-body\">\n                  <div class=\"sii-m-accordion__body__contents\">\n                    <ul>\n<li>Stra\u00dfenbahnhaltestelle in der N\u00e4he vom B\u00fcro<\/li>\n<li>Bushaltestelle in der N\u00e4he vom B\u00fcro<\/li>\n<li>Hauptbahnhof und Busbahnhof 2 km vom B\u00fcro entfernt<\/li>\n<\/ul>\n\n                  <\/div>\n              <\/div>\n          <\/div>\n                  <div class=\"sii-m-accordion__item js-accordion-item \">\n              <button class=\"sii-m-accordion__header js-accordion-header\">\n                  <div class=\"sii-m-accordion__header__icon\">\n                      <svg width=\"22\" height=\"14\" viewBox=\"0 0 22 14\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M17.5734 6.16418C17.1431 6.16418 16.7293 6.24142 16.3431 6.37383L14.7322 3.15192L13.7777 1.24305H16.2604C16.7127 1.24305 17.0769 1.61269 17.0769 2.05956C17.0769 2.33541 17.2975 2.55609 17.5734 2.55609C17.8492 2.55609 18.0699 2.33541 18.0699 2.05956C18.0699 1.06099 17.2589 0.25 16.2604 0.25H12.9722C12.8012 0.25 12.6412 0.338271 12.5474 0.487229C12.4537 0.636187 12.4481 0.818247 12.5254 0.972722L13.7281 3.37812L10.9972 8.83991L8.15594 3.15744L7.20151 1.24857H8.37111C8.64695 1.24857 8.86763 1.02789 8.86763 0.752043C8.86763 0.476195 8.64695 0.255517 8.37111 0.255517H5.083C4.80715 0.255517 4.58647 0.476195 4.58647 0.752043C4.58647 1.02789 4.80715 1.24857 5.083 1.24857H6.0926L7.15737 3.38363L5.65676 6.38486C5.27057 6.25245 4.8568 6.17521 4.42648 6.17521C2.34107 6.17521 0.641846 7.87444 0.641846 9.95985C0.641846 12.0453 2.34107 13.7445 4.42648 13.7445C6.34638 13.7445 7.92975 12.3101 8.1725 10.4564H10.9972C11.0468 10.4564 11.0965 10.4453 11.1461 10.4343C11.1572 10.4343 11.1627 10.4288 11.1737 10.4233C11.2234 10.4067 11.2675 10.3791 11.3061 10.3516C11.3116 10.346 11.3227 10.3405 11.3282 10.335C11.3613 10.3019 11.3944 10.2688 11.422 10.2247C11.422 10.2136 11.4275 10.2081 11.433 10.1971C11.433 10.1971 11.4385 10.1916 11.4441 10.186L14.2853 4.50358L15.4494 6.83725C14.4453 7.51584 13.7888 8.66888 13.7888 9.96537C13.7888 12.0508 15.488 13.75 17.5734 13.75C19.6588 13.75 21.358 12.0508 21.358 9.96537C21.358 7.87996 19.6588 6.18073 17.5734 6.18073V6.16418ZM4.432 12.7404C2.89277 12.7404 1.64042 11.488 1.64042 9.94881C1.64042 8.40958 2.89277 7.15723 4.432 7.15723C4.70233 7.15723 4.96163 7.20689 5.20989 7.27861L3.99064 9.72262C3.9134 9.87709 3.92444 10.0592 4.01271 10.2081C4.10098 10.3571 4.26097 10.4453 4.43751 10.4453H7.17944C6.94221 11.7473 5.80572 12.7404 4.43751 12.7404H4.432ZM7.16841 9.45229H5.23196L6.09812 7.72548C6.64981 8.13925 7.04152 8.74612 7.16841 9.45229ZM8.17801 9.45229C8.03457 8.35993 7.42219 7.41101 6.55051 6.8207L7.71459 4.48702L10.1972 9.45229H8.1725H8.17801ZM17.5734 12.7404C16.0342 12.7404 14.7818 11.488 14.7818 9.94881C14.7818 9.03852 15.2287 8.23304 15.9073 7.72548L17.132 10.1695C17.2203 10.346 17.3969 10.4453 17.5789 10.4453C17.6561 10.4453 17.7279 10.4288 17.7996 10.3902C18.0423 10.2688 18.1416 9.97088 18.0203 9.72262L16.801 7.27861C17.0493 7.20689 17.3086 7.15723 17.5789 7.15723C19.1181 7.15723 20.3705 8.40958 20.3705 9.94881C20.3705 11.488 19.1181 12.7404 17.5789 12.7404H17.5734Z\" \/>\n<\/svg>\n\n                  <\/div>\n                  <div class=\"sii-m-accordion__header__text\">\n                      F\u00fcr Radfahrer \n                  <\/div>\n                  <div class=\"sii-m-accordion__header__arrow\">\n                      <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" viewBox=\"0 0 12 7\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Sites\">\n    <g id=\"Sites-_-Gdansk\" data-name=\"Sites-&amp;gt;-Gdansk\">\n      <polygon id=\"Path-Copy-3\" class=\"cls-1\" points=\"1.4 0 6 4.3 10.6 0 12 1.3 6 7 0 1.3 1.4 0\"\/>\n    <\/g>\n  <\/g>\n<\/svg>\n                  <\/div>\n              <\/button>\n              <div class=\"sii-m-accordion__body js-accordion-body\">\n                  <div class=\"sii-m-accordion__body__contents\">\n                    <ul>\n<li>Citybikes und Roller erh\u00e4ltlich in der N\u00e4he vom B\u00fcro<\/li>\n<\/ul>\n\n                  <\/div>\n              <\/div>\n          <\/div>\n              <\/div>\n                <img decoding=\"async\" class=\"sii-o-panel-horizontal-map__map top u-hidden-on-medium-large\" src=\"https:\/\/sii.pl\/wp-content\/uploads\/2019\/12\/Wroclaw-1.jpg\" alt=\"Wroclaw - office\">\n                    <img decoding=\"async\" class=\"sii-o-panel-horizontal-map__map top u-hidden-on-desktop-small\" src=\"https:\/\/sii.pl\/wp-content\/uploads\/2019\/12\/Wroclaw_mobile-1.jpg\" alt=\"Wroclaw - office, mobile\">\n        <\/div>\n<\/div>\n<\/section>\n\n\n<div class=\"nsw-o-thumbnails-gallery  js-slider js-slider-autoplay-fast js-slider-show_4 js-slider-show-tablet_3 js-slider-show-mobile_2\">\n    <div class=\"nsw-o-thumbnails-gallery__content d-flex js-carousel\">\n                    <div class=\"nsw-o-thumbnails-gallery__slide\">\n                <img decoding=\"async\" src=\"https:\/\/sii.pl\/wp-content\/uploads\/2022\/06\/07ea2e59-9403-497b-ac11-f0690f3ecf29.jpg\" alt=\"Sii Wroc\u0142aw Team\">\n            <\/div>\n                    <div class=\"nsw-o-thumbnails-gallery__slide\">\n                <img decoding=\"async\" src=\"https:\/\/sii.pl\/wp-content\/uploads\/2019\/12\/WRO_06.jpg\" alt=\"\">\n            <\/div>\n                    <div class=\"nsw-o-thumbnails-gallery__slide\">\n                <img decoding=\"async\" src=\"https:\/\/sii.pl\/wp-content\/uploads\/2022\/06\/fc8dfd72-6563-4d29-8a5c-dce64440b87e.jpg\" alt=\"Zbigniew (Account Executive), Ewa (Regional Recruitment Department Manager)\">\n            <\/div>\n                    <div class=\"nsw-o-thumbnails-gallery__slide\">\n                <img decoding=\"async\" src=\"https:\/\/sii.pl\/wp-content\/uploads\/2019\/12\/WRO_10.jpg\" alt=\"\">\n            <\/div>\n                    <div class=\"nsw-o-thumbnails-gallery__slide\">\n                <img decoding=\"async\" src=\"https:\/\/sii.pl\/wp-content\/uploads\/2019\/12\/WRO_09.jpg\" alt=\"\">\n            <\/div>\n                    <div class=\"nsw-o-thumbnails-gallery__slide\">\n                <img decoding=\"async\" src=\"https:\/\/sii.pl\/wp-content\/uploads\/2019\/12\/WRO_01.jpg\" alt=\"\">\n            <\/div>\n                    <div class=\"nsw-o-thumbnails-gallery__slide\">\n                <img decoding=\"async\" src=\"https:\/\/sii.pl\/wp-content\/uploads\/2019\/12\/WRO_05.jpg\" alt=\"\">\n            <\/div>\n                    <div class=\"nsw-o-thumbnails-gallery__slide\">\n                <img decoding=\"async\" src=\"https:\/\/sii.pl\/wp-content\/uploads\/2019\/12\/WRO_02.jpg\" alt=\"\">\n            <\/div>\n            <\/div>\n<\/div>\n\n\n<section class=\"wp-block-nsw-block-section nsw-section  section-50b3e51f-d26d-491f-bf1c-7619e1c60710\" id=\"\"><style type=\"text\/css\">.section-50b3e51f-d26d-491f-bf1c-7619e1c60710 { padding-top:50px;padding-bottom:50px; }\n     \t\t\t\t\t @media screen and (max-width: 991px) { .section-50b3e51f-d26d-491f-bf1c-7619e1c60710 { padding-top:40px;padding-bottom:72px; } }<\/style>\n<div class=\"wp-block-sii-nsw-container container container-07fbfd59-63e6-4aae-8193-a481f9957951\"><style type=\"text\/css\">.container-07fbfd59-63e6-4aae-8193-a481f9957951 {  }\n                         @media screen and (max-width: 991px) { .container-07fbfd59-63e6-4aae-8193-a481f9957951 {  } }<\/style><style>\n    \/* .wp-admin .nsw-o-ads-grid{ *\/\n    .editor-styles-wrapper .nsw-o-ads-grid .nsw-a-label__list{\n        padding:0;\n    }\n    .editor-styles-wrapper .nsw-o-ads-grid a:hover{\n        text-decoration: none!important;\n    }\n<\/style>\n\n\n                        <div class=\"nsw-o-ads-suggestions\">\n        <div class=\"nsw-m-title-block -has-title-mark-color-gradient-main -has-subtitle-mark-color-gradient-main -h2 -p1\">\n                                <h2 class=\"nsw-m-title-block__title\"><mark>WERDE TEIL<\/mark> UNSERES TEAMS<\/h2>\n                        <p class=\"nsw-m-title-block__subtitle\">Entdecke unsere Jobangebote in Wroc\u0142aw<\/p>\n    <\/div>\n        <div class=\"nsw-o-slider -ads-suggestions js-slider js-slider-show_2 js-slider-show-tablet_2 js-slider-show-mobile_1 js-slider-rows-mobile_1 js-slider-custom-dots js-slider-custom-dots-append\">\n        <div class=\"nsw-o-slider__navigation u-hidden-on-desktop\">\n            <button  class=\"nsw-a-icon-button -transparent nsw-o-slider__prev  u-hidden-on-desktop js-slide-prev\" aria-label=\"Show previous slide\">\n    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path d=\"M 19.03125 4.28125 L 8.03125 15.28125 L 7.34375 16 L 8.03125 16.71875 L 19.03125 27.71875 L 20.46875 26.28125 L 10.1875 16 L 20.46875 5.71875 Z\"\/><\/svg>\n\n    <\/button>\n            <button  class=\"nsw-a-icon-button -transparent nsw-o-slider__next  u-hidden-on-desktop js-slide-next\" aria-label=\"Show next slide\">\n      <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 32 32\" id=\"angle-right\">\n    <title>angle-right<\/title>\n    <path d=\"M12.969 4.281l11 11 .688.719-.688.719-11 11-1.438-1.438L21.812 16 11.531 5.719z\"><\/path>\n  <\/svg>\n\n    <\/button>\n        <\/div>\n        <div class=\"nsw-o-slider__content d-flex flex-row js-carousel\">\n                            <div class=\"nsw-o-slider__slide\">\n                    <a class=\"nsw-o-slider__item d-block u-color-nswc-grey-1000 text-decoration-none\" href=\"https:\/\/sii.pl\/en\/job-ads\/id\/37963\/senior-test-manager-large-scale-migration-program-f-m-x\">\n                        <div class=\"nsw-m-job-add-card \">\n            <h3 class=\"nsw-m-job-add-card__title\">Senior Test Manager &#8211; Large-Scale Migration Program (f\/m\/x)<\/h3>\n        <div class=\"nsw-m-job-add-card__labels d-flex flex-column flex-lg-row justify-content-start\">\n                    <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <path id=\"Path_2082\" data-name=\"Path 2082\" class=\"cls-1\" d=\"m11.64,20.54v-7.47h-7.47L12.7,4.54h7.47v7.47l-8.53,8.53Zm5.07-7.31l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Zm-3.47,3.47l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Z\"\/>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Senior<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2239\" data-name=\"Group 2239\">\n    <path id=\"Path_2083\" data-name=\"Path 2083\" class=\"cls-1\" d=\"m6.99,19.4c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.46-.47,1.1-.74,1.76-.72,1.37,0,2.49,1.12,2.48,2.49,0,.66-.26,1.28-.72,1.75-.46.47-1.1.74-1.76.72Zm11.03,0c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.98-.96,2.55-.95,3.52.03.95.97.95,2.52,0,3.48-.46.47-1.1.74-1.76.72Zm-5.52-8.83c-1.37,0-2.48-1.1-2.48-2.46,0,0,0-.01,0-.02,0-1.37,1.1-2.48,2.46-2.48,0,0,.01,0,.02,0,1.37,0,2.48,1.1,2.48,2.46,0,0,0,.01,0,.02,0,1.37-1.1,2.48-2.46,2.48,0,0-.01,0-.02,0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Remote,&nbsp;<\/li>\n                \n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Hybrid,&nbsp;<\/li>\n                \n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Office<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small -locations d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2240\" data-name=\"Group 2240\">\n    <path id=\"Path_2084\" data-name=\"Path 2084\" class=\"cls-1\" d=\"m12.5,12.54c.91,0,1.64-.74,1.64-1.64,0-.91-.74-1.64-1.64-1.64-.44,0-.85.17-1.16.48-.64.64-.64,1.68,0,2.32.31.31.73.48,1.16.48h0Zm0,5.72c1.35-1.18,2.55-2.53,3.57-4.01.68-.93,1.07-2.04,1.15-3.19.05-1.31-.44-2.59-1.36-3.53-.89-.89-2.1-1.38-3.36-1.35-1.26-.03-2.48.46-3.36,1.35-.92.94-1.41,2.22-1.36,3.53.08,1.15.47,2.25,1.15,3.19,1.02,1.48,2.22,2.83,3.57,4.01h0Zm0,2.24c-1.81-1.49-3.43-3.21-4.81-5.1-.96-1.25-1.51-2.76-1.59-4.34-.09-1.8.61-3.55,1.92-4.79,1.21-1.15,2.81-1.79,4.48-1.77,1.67-.02,3.27.62,4.48,1.77,1.31,1.24,2.01,2.99,1.92,4.79-.08,1.57-.63,3.08-1.59,4.34-1.38,1.89-3,3.61-4.81,5.1h0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                    <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">Multiple locations<\/li>\n                        <\/ul>\n    <\/span>\n            <\/div>\n<\/div>\n                    <\/a>\n                <\/div>\n                            <div class=\"nsw-o-slider__slide\">\n                    <a class=\"nsw-o-slider__item d-block u-color-nswc-grey-1000 text-decoration-none\" href=\"https:\/\/sii.pl\/en\/job-ads\/id\/37961\/signal-processing-data-analysis-specialist-f-m-x\">\n                        <div class=\"nsw-m-job-add-card \">\n            <h3 class=\"nsw-m-job-add-card__title\">Signal Processing &amp; Data Analysis Specialist (f\/m\/x)<\/h3>\n        <div class=\"nsw-m-job-add-card__labels d-flex flex-column flex-lg-row justify-content-start\">\n                    <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <path id=\"Path_2082\" data-name=\"Path 2082\" class=\"cls-1\" d=\"m11.64,20.54v-7.47h-7.47L12.7,4.54h7.47v7.47l-8.53,8.53Zm5.07-7.31l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Zm-3.47,3.47l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Z\"\/>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Senior<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2239\" data-name=\"Group 2239\">\n    <path id=\"Path_2083\" data-name=\"Path 2083\" class=\"cls-1\" d=\"m6.99,19.4c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.46-.47,1.1-.74,1.76-.72,1.37,0,2.49,1.12,2.48,2.49,0,.66-.26,1.28-.72,1.75-.46.47-1.1.74-1.76.72Zm11.03,0c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.98-.96,2.55-.95,3.52.03.95.97.95,2.52,0,3.48-.46.47-1.1.74-1.76.72Zm-5.52-8.83c-1.37,0-2.48-1.1-2.48-2.46,0,0,0-.01,0-.02,0-1.37,1.1-2.48,2.46-2.48,0,0,.01,0,.02,0,1.37,0,2.48,1.1,2.48,2.46,0,0,0,.01,0,.02,0,1.37-1.1,2.48-2.46,2.48,0,0-.01,0-.02,0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Remote<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small -locations d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2240\" data-name=\"Group 2240\">\n    <path id=\"Path_2084\" data-name=\"Path 2084\" class=\"cls-1\" d=\"m12.5,12.54c.91,0,1.64-.74,1.64-1.64,0-.91-.74-1.64-1.64-1.64-.44,0-.85.17-1.16.48-.64.64-.64,1.68,0,2.32.31.31.73.48,1.16.48h0Zm0,5.72c1.35-1.18,2.55-2.53,3.57-4.01.68-.93,1.07-2.04,1.15-3.19.05-1.31-.44-2.59-1.36-3.53-.89-.89-2.1-1.38-3.36-1.35-1.26-.03-2.48.46-3.36,1.35-.92.94-1.41,2.22-1.36,3.53.08,1.15.47,2.25,1.15,3.19,1.02,1.48,2.22,2.83,3.57,4.01h0Zm0,2.24c-1.81-1.49-3.43-3.21-4.81-5.1-.96-1.25-1.51-2.76-1.59-4.34-.09-1.8.61-3.55,1.92-4.79,1.21-1.15,2.81-1.79,4.48-1.77,1.67-.02,3.27.62,4.48,1.77,1.31,1.24,2.01,2.99,1.92,4.79-.08,1.57-.63,3.08-1.59,4.34-1.38,1.89-3,3.61-4.81,5.1h0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                    <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">Multiple locations<\/li>\n                        <\/ul>\n    <\/span>\n            <\/div>\n<\/div>\n                    <\/a>\n                <\/div>\n                            <div class=\"nsw-o-slider__slide\">\n                    <a class=\"nsw-o-slider__item d-block u-color-nswc-grey-1000 text-decoration-none\" href=\"https:\/\/sii.pl\/en\/job-ads\/id\/37960\/senior-c-developer-z-qt-f-m-x\">\n                        <div class=\"nsw-m-job-add-card \">\n            <h3 class=\"nsw-m-job-add-card__title\">Senior C++ Developer z QT (f\/m\/x)<\/h3>\n        <div class=\"nsw-m-job-add-card__labels d-flex flex-column flex-lg-row justify-content-start\">\n                    <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <path id=\"Path_2082\" data-name=\"Path 2082\" class=\"cls-1\" d=\"m11.64,20.54v-7.47h-7.47L12.7,4.54h7.47v7.47l-8.53,8.53Zm5.07-7.31l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Zm-3.47,3.47l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Z\"\/>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Senior<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2239\" data-name=\"Group 2239\">\n    <path id=\"Path_2083\" data-name=\"Path 2083\" class=\"cls-1\" d=\"m6.99,19.4c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.46-.47,1.1-.74,1.76-.72,1.37,0,2.49,1.12,2.48,2.49,0,.66-.26,1.28-.72,1.75-.46.47-1.1.74-1.76.72Zm11.03,0c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.98-.96,2.55-.95,3.52.03.95.97.95,2.52,0,3.48-.46.47-1.1.74-1.76.72Zm-5.52-8.83c-1.37,0-2.48-1.1-2.48-2.46,0,0,0-.01,0-.02,0-1.37,1.1-2.48,2.46-2.48,0,0,.01,0,.02,0,1.37,0,2.48,1.1,2.48,2.46,0,0,0,.01,0,.02,0,1.37-1.1,2.48-2.46,2.48,0,0-.01,0-.02,0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Remote,&nbsp;<\/li>\n                \n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Hybrid,&nbsp;<\/li>\n                \n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Office<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small -locations d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2240\" data-name=\"Group 2240\">\n    <path id=\"Path_2084\" data-name=\"Path 2084\" class=\"cls-1\" d=\"m12.5,12.54c.91,0,1.64-.74,1.64-1.64,0-.91-.74-1.64-1.64-1.64-.44,0-.85.17-1.16.48-.64.64-.64,1.68,0,2.32.31.31.73.48,1.16.48h0Zm0,5.72c1.35-1.18,2.55-2.53,3.57-4.01.68-.93,1.07-2.04,1.15-3.19.05-1.31-.44-2.59-1.36-3.53-.89-.89-2.1-1.38-3.36-1.35-1.26-.03-2.48.46-3.36,1.35-.92.94-1.41,2.22-1.36,3.53.08,1.15.47,2.25,1.15,3.19,1.02,1.48,2.22,2.83,3.57,4.01h0Zm0,2.24c-1.81-1.49-3.43-3.21-4.81-5.1-.96-1.25-1.51-2.76-1.59-4.34-.09-1.8.61-3.55,1.92-4.79,1.21-1.15,2.81-1.79,4.48-1.77,1.67-.02,3.27.62,4.48,1.77,1.31,1.24,2.01,2.99,1.92,4.79-.08,1.57-.63,3.08-1.59,4.34-1.38,1.89-3,3.61-4.81,5.1h0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                    <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">Multiple locations<\/li>\n                        <\/ul>\n    <\/span>\n            <\/div>\n<\/div>\n                    <\/a>\n                <\/div>\n                            <div class=\"nsw-o-slider__slide\">\n                    <a class=\"nsw-o-slider__item d-block u-color-nswc-grey-1000 text-decoration-none\" href=\"https:\/\/sii.pl\/en\/job-ads\/id\/37956\/senior-test-automation-engineer-with-c-f-m-x\">\n                        <div class=\"nsw-m-job-add-card \">\n            <h3 class=\"nsw-m-job-add-card__title\">Senior Test Automation Engineer with C# (f\/m\/x)<\/h3>\n        <div class=\"nsw-m-job-add-card__labels d-flex flex-column flex-lg-row justify-content-start\">\n                    <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <path id=\"Path_2082\" data-name=\"Path 2082\" class=\"cls-1\" d=\"m11.64,20.54v-7.47h-7.47L12.7,4.54h7.47v7.47l-8.53,8.53Zm5.07-7.31l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Zm-3.47,3.47l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Z\"\/>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Senior<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2239\" data-name=\"Group 2239\">\n    <path id=\"Path_2083\" data-name=\"Path 2083\" class=\"cls-1\" d=\"m6.99,19.4c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.46-.47,1.1-.74,1.76-.72,1.37,0,2.49,1.12,2.48,2.49,0,.66-.26,1.28-.72,1.75-.46.47-1.1.74-1.76.72Zm11.03,0c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.98-.96,2.55-.95,3.52.03.95.97.95,2.52,0,3.48-.46.47-1.1.74-1.76.72Zm-5.52-8.83c-1.37,0-2.48-1.1-2.48-2.46,0,0,0-.01,0-.02,0-1.37,1.1-2.48,2.46-2.48,0,0,.01,0,.02,0,1.37,0,2.48,1.1,2.48,2.46,0,0,0,.01,0,.02,0,1.37-1.1,2.48-2.46,2.48,0,0-.01,0-.02,0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Hybrid,&nbsp;<\/li>\n                \n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Office<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small -locations d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2240\" data-name=\"Group 2240\">\n    <path id=\"Path_2084\" data-name=\"Path 2084\" class=\"cls-1\" d=\"m12.5,12.54c.91,0,1.64-.74,1.64-1.64,0-.91-.74-1.64-1.64-1.64-.44,0-.85.17-1.16.48-.64.64-.64,1.68,0,2.32.31.31.73.48,1.16.48h0Zm0,5.72c1.35-1.18,2.55-2.53,3.57-4.01.68-.93,1.07-2.04,1.15-3.19.05-1.31-.44-2.59-1.36-3.53-.89-.89-2.1-1.38-3.36-1.35-1.26-.03-2.48.46-3.36,1.35-.92.94-1.41,2.22-1.36,3.53.08,1.15.47,2.25,1.15,3.19,1.02,1.48,2.22,2.83,3.57,4.01h0Zm0,2.24c-1.81-1.49-3.43-3.21-4.81-5.1-.96-1.25-1.51-2.76-1.59-4.34-.09-1.8.61-3.55,1.92-4.79,1.21-1.15,2.81-1.79,4.48-1.77,1.67-.02,3.27.62,4.48,1.77,1.31,1.24,2.01,2.99,1.92,4.79-.08,1.57-.63,3.08-1.59,4.34-1.38,1.89-3,3.61-4.81,5.1h0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                    <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">Wroclaw<\/li>\n                        <\/ul>\n    <\/span>\n            <\/div>\n<\/div>\n                    <\/a>\n                <\/div>\n                            <div class=\"nsw-o-slider__slide\">\n                    <a class=\"nsw-o-slider__item d-block u-color-nswc-grey-1000 text-decoration-none\" href=\"https:\/\/sii.pl\/en\/job-ads\/id\/37953\/senior-training-project-manager-f-m-x\">\n                        <div class=\"nsw-m-job-add-card \">\n            <h3 class=\"nsw-m-job-add-card__title\">Senior Training Project Manager (f\/m\/x)<\/h3>\n        <div class=\"nsw-m-job-add-card__labels d-flex flex-column flex-lg-row justify-content-start\">\n                    <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <path id=\"Path_2082\" data-name=\"Path 2082\" class=\"cls-1\" d=\"m11.64,20.54v-7.47h-7.47L12.7,4.54h7.47v7.47l-8.53,8.53Zm5.07-7.31l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Zm-3.47,3.47l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Z\"\/>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Senior<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2239\" data-name=\"Group 2239\">\n    <path id=\"Path_2083\" data-name=\"Path 2083\" class=\"cls-1\" d=\"m6.99,19.4c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.46-.47,1.1-.74,1.76-.72,1.37,0,2.49,1.12,2.48,2.49,0,.66-.26,1.28-.72,1.75-.46.47-1.1.74-1.76.72Zm11.03,0c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.98-.96,2.55-.95,3.52.03.95.97.95,2.52,0,3.48-.46.47-1.1.74-1.76.72Zm-5.52-8.83c-1.37,0-2.48-1.1-2.48-2.46,0,0,0-.01,0-.02,0-1.37,1.1-2.48,2.46-2.48,0,0,.01,0,.02,0,1.37,0,2.48,1.1,2.48,2.46,0,0,0,.01,0,.02,0,1.37-1.1,2.48-2.46,2.48,0,0-.01,0-.02,0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Hybrid,&nbsp;<\/li>\n                \n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Office<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small -locations d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2240\" data-name=\"Group 2240\">\n    <path id=\"Path_2084\" data-name=\"Path 2084\" class=\"cls-1\" d=\"m12.5,12.54c.91,0,1.64-.74,1.64-1.64,0-.91-.74-1.64-1.64-1.64-.44,0-.85.17-1.16.48-.64.64-.64,1.68,0,2.32.31.31.73.48,1.16.48h0Zm0,5.72c1.35-1.18,2.55-2.53,3.57-4.01.68-.93,1.07-2.04,1.15-3.19.05-1.31-.44-2.59-1.36-3.53-.89-.89-2.1-1.38-3.36-1.35-1.26-.03-2.48.46-3.36,1.35-.92.94-1.41,2.22-1.36,3.53.08,1.15.47,2.25,1.15,3.19,1.02,1.48,2.22,2.83,3.57,4.01h0Zm0,2.24c-1.81-1.49-3.43-3.21-4.81-5.1-.96-1.25-1.51-2.76-1.59-4.34-.09-1.8.61-3.55,1.92-4.79,1.21-1.15,2.81-1.79,4.48-1.77,1.67-.02,3.27.62,4.48,1.77,1.31,1.24,2.01,2.99,1.92,4.79-.08,1.57-.63,3.08-1.59,4.34-1.38,1.89-3,3.61-4.81,5.1h0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                    <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">Multiple locations<\/li>\n                        <\/ul>\n    <\/span>\n            <\/div>\n<\/div>\n                    <\/a>\n                <\/div>\n                            <div class=\"nsw-o-slider__slide\">\n                    <a class=\"nsw-o-slider__item d-block u-color-nswc-grey-1000 text-decoration-none\" href=\"https:\/\/sii.pl\/en\/job-ads\/id\/37945\/senior-servicenow-developer-ai-automation-f-m-x\">\n                        <div class=\"nsw-m-job-add-card \">\n            <h3 class=\"nsw-m-job-add-card__title\">Senior ServiceNow Developer\u2013 AI &amp; Automation (f\/m\/x)<\/h3>\n        <div class=\"nsw-m-job-add-card__labels d-flex flex-column flex-lg-row justify-content-start\">\n                    <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <path id=\"Path_2082\" data-name=\"Path 2082\" class=\"cls-1\" d=\"m11.64,20.54v-7.47h-7.47L12.7,4.54h7.47v7.47l-8.53,8.53Zm5.07-7.31l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Zm-3.47,3.47l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Z\"\/>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Senior<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2239\" data-name=\"Group 2239\">\n    <path id=\"Path_2083\" data-name=\"Path 2083\" class=\"cls-1\" d=\"m6.99,19.4c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.46-.47,1.1-.74,1.76-.72,1.37,0,2.49,1.12,2.48,2.49,0,.66-.26,1.28-.72,1.75-.46.47-1.1.74-1.76.72Zm11.03,0c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.98-.96,2.55-.95,3.52.03.95.97.95,2.52,0,3.48-.46.47-1.1.74-1.76.72Zm-5.52-8.83c-1.37,0-2.48-1.1-2.48-2.46,0,0,0-.01,0-.02,0-1.37,1.1-2.48,2.46-2.48,0,0,.01,0,.02,0,1.37,0,2.48,1.1,2.48,2.46,0,0,0,.01,0,.02,0,1.37-1.1,2.48-2.46,2.48,0,0-.01,0-.02,0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Remote,&nbsp;<\/li>\n                \n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Hybrid,&nbsp;<\/li>\n                \n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Office<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small -locations d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2240\" data-name=\"Group 2240\">\n    <path id=\"Path_2084\" data-name=\"Path 2084\" class=\"cls-1\" d=\"m12.5,12.54c.91,0,1.64-.74,1.64-1.64,0-.91-.74-1.64-1.64-1.64-.44,0-.85.17-1.16.48-.64.64-.64,1.68,0,2.32.31.31.73.48,1.16.48h0Zm0,5.72c1.35-1.18,2.55-2.53,3.57-4.01.68-.93,1.07-2.04,1.15-3.19.05-1.31-.44-2.59-1.36-3.53-.89-.89-2.1-1.38-3.36-1.35-1.26-.03-2.48.46-3.36,1.35-.92.94-1.41,2.22-1.36,3.53.08,1.15.47,2.25,1.15,3.19,1.02,1.48,2.22,2.83,3.57,4.01h0Zm0,2.24c-1.81-1.49-3.43-3.21-4.81-5.1-.96-1.25-1.51-2.76-1.59-4.34-.09-1.8.61-3.55,1.92-4.79,1.21-1.15,2.81-1.79,4.48-1.77,1.67-.02,3.27.62,4.48,1.77,1.31,1.24,2.01,2.99,1.92,4.79-.08,1.57-.63,3.08-1.59,4.34-1.38,1.89-3,3.61-4.81,5.1h0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                    <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">Multiple locations<\/li>\n                        <\/ul>\n    <\/span>\n            <\/div>\n<\/div>\n                    <\/a>\n                <\/div>\n                            <div class=\"nsw-o-slider__slide\">\n                    <a class=\"nsw-o-slider__item d-block u-color-nswc-grey-1000 text-decoration-none\" href=\"https:\/\/sii.pl\/en\/job-ads\/id\/37944\/business-manager-healthcare-industry-f-m-x\">\n                        <div class=\"nsw-m-job-add-card \">\n            <h3 class=\"nsw-m-job-add-card__title\">Business Manager &#8211; Healthcare Industry (f\/m\/x)<\/h3>\n        <div class=\"nsw-m-job-add-card__labels d-flex flex-column flex-lg-row justify-content-start\">\n                    <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <path id=\"Path_2082\" data-name=\"Path 2082\" class=\"cls-1\" d=\"m11.64,20.54v-7.47h-7.47L12.7,4.54h7.47v7.47l-8.53,8.53Zm5.07-7.31l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Zm-3.47,3.47l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Z\"\/>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Senior<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2239\" data-name=\"Group 2239\">\n    <path id=\"Path_2083\" data-name=\"Path 2083\" class=\"cls-1\" d=\"m6.99,19.4c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.46-.47,1.1-.74,1.76-.72,1.37,0,2.49,1.12,2.48,2.49,0,.66-.26,1.28-.72,1.75-.46.47-1.1.74-1.76.72Zm11.03,0c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.98-.96,2.55-.95,3.52.03.95.97.95,2.52,0,3.48-.46.47-1.1.74-1.76.72Zm-5.52-8.83c-1.37,0-2.48-1.1-2.48-2.46,0,0,0-.01,0-.02,0-1.37,1.1-2.48,2.46-2.48,0,0,.01,0,.02,0,1.37,0,2.48,1.1,2.48,2.46,0,0,0,.01,0,.02,0,1.37-1.1,2.48-2.46,2.48,0,0-.01,0-.02,0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Hybrid,&nbsp;<\/li>\n                \n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Office<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small -locations d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2240\" data-name=\"Group 2240\">\n    <path id=\"Path_2084\" data-name=\"Path 2084\" class=\"cls-1\" d=\"m12.5,12.54c.91,0,1.64-.74,1.64-1.64,0-.91-.74-1.64-1.64-1.64-.44,0-.85.17-1.16.48-.64.64-.64,1.68,0,2.32.31.31.73.48,1.16.48h0Zm0,5.72c1.35-1.18,2.55-2.53,3.57-4.01.68-.93,1.07-2.04,1.15-3.19.05-1.31-.44-2.59-1.36-3.53-.89-.89-2.1-1.38-3.36-1.35-1.26-.03-2.48.46-3.36,1.35-.92.94-1.41,2.22-1.36,3.53.08,1.15.47,2.25,1.15,3.19,1.02,1.48,2.22,2.83,3.57,4.01h0Zm0,2.24c-1.81-1.49-3.43-3.21-4.81-5.1-.96-1.25-1.51-2.76-1.59-4.34-.09-1.8.61-3.55,1.92-4.79,1.21-1.15,2.81-1.79,4.48-1.77,1.67-.02,3.27.62,4.48,1.77,1.31,1.24,2.01,2.99,1.92,4.79-.08,1.57-.63,3.08-1.59,4.34-1.38,1.89-3,3.61-4.81,5.1h0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                    <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">Multiple locations<\/li>\n                        <\/ul>\n    <\/span>\n            <\/div>\n<\/div>\n                    <\/a>\n                <\/div>\n                            <div class=\"nsw-o-slider__slide\">\n                    <a class=\"nsw-o-slider__item d-block u-color-nswc-grey-1000 text-decoration-none\" href=\"https:\/\/sii.pl\/en\/job-ads\/id\/37943\/manual-tester-with-murex-platform-knowledge-f-m-x\">\n                        <div class=\"nsw-m-job-add-card \">\n            <h3 class=\"nsw-m-job-add-card__title\">Manual Tester with Murex Platform Knowledge (f\/m\/x)<\/h3>\n        <div class=\"nsw-m-job-add-card__labels d-flex flex-column flex-lg-row justify-content-start\">\n                    <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <path id=\"Path_2082\" data-name=\"Path 2082\" class=\"cls-1\" d=\"m11.64,20.54v-7.47h-7.47L12.7,4.54h7.47v7.47l-8.53,8.53Zm5.07-7.31l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Zm-3.47,3.47l1.87-1.87v-5.22h-5.22l-1.87,1.87h5.22v5.22Z\"\/>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Regular,&nbsp;<\/li>\n                \n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Senior<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2239\" data-name=\"Group 2239\">\n    <path id=\"Path_2083\" data-name=\"Path 2083\" class=\"cls-1\" d=\"m6.99,19.4c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.46-.47,1.1-.74,1.76-.72,1.37,0,2.49,1.12,2.48,2.49,0,.66-.26,1.28-.72,1.75-.46.47-1.1.74-1.76.72Zm11.03,0c-1.37,0-2.49-1.12-2.48-2.49,0-.66.26-1.28.72-1.75.98-.96,2.55-.95,3.52.03.95.97.95,2.52,0,3.48-.46.47-1.1.74-1.76.72Zm-5.52-8.83c-1.37,0-2.48-1.1-2.48-2.46,0,0,0-.01,0-.02,0-1.37,1.1-2.48,2.46-2.48,0,0,.01,0,.02,0,1.37,0,2.48,1.1,2.48,2.46,0,0,0,.01,0,.02,0,1.37-1.1,2.48-2.46,2.48,0,0-.01,0-.02,0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Remote,&nbsp;<\/li>\n                \n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Hybrid,&nbsp;<\/li>\n                \n                                                <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">\n                        Office<\/li>\n                \n                        \n                \n             \n                        \n                    \n                        \n                    \n         \n            \n    <\/ul>\n    <\/span>\n                            <span class=\"nsw-a-label -icon -primary -label-small -locations d-flex align-items-center\">\n            <div class=\"nsw-a-label__icon d-flex align-items-center\">\n            <?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<svg id=\"Warstwa_1\" data-name=\"Warstwa 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 25\">\n  <defs>\n    <style>\n      .cls-1 {\n        stroke-width: 0px;\n      }\n    <\/style>\n  <\/defs>\n  <g id=\"Group_2240\" data-name=\"Group 2240\">\n    <path id=\"Path_2084\" data-name=\"Path 2084\" class=\"cls-1\" d=\"m12.5,12.54c.91,0,1.64-.74,1.64-1.64,0-.91-.74-1.64-1.64-1.64-.44,0-.85.17-1.16.48-.64.64-.64,1.68,0,2.32.31.31.73.48,1.16.48h0Zm0,5.72c1.35-1.18,2.55-2.53,3.57-4.01.68-.93,1.07-2.04,1.15-3.19.05-1.31-.44-2.59-1.36-3.53-.89-.89-2.1-1.38-3.36-1.35-1.26-.03-2.48.46-3.36,1.35-.92.94-1.41,2.22-1.36,3.53.08,1.15.47,2.25,1.15,3.19,1.02,1.48,2.22,2.83,3.57,4.01h0Zm0,2.24c-1.81-1.49-3.43-3.21-4.81-5.1-.96-1.25-1.51-2.76-1.59-4.34-.09-1.8.61-3.55,1.92-4.79,1.21-1.15,2.81-1.79,4.48-1.77,1.67-.02,3.27.62,4.48,1.77,1.31,1.24,2.01,2.99,1.92,4.79-.08,1.57-.63,3.08-1.59,4.34-1.38,1.89-3,3.61-4.81,5.1h0Z\"\/>\n  <\/g>\n<\/svg>\n        <\/div>\n    \n        <ul class=\"nsw-a-label__list d-flex\">\n                                    <li class=\"d-inline-block u-color-nswc-grey-600 u-font-regular\">Multiple locations<\/li>\n                        <\/ul>\n    <\/span>\n            <\/div>\n<\/div>\n                    <\/a>\n                <\/div>\n                    <\/div>\n        <div class=\"nsw-o-slider__dots  js-slider-custom-dots-append-container\">\n                        <div class=\"nsw-o-slider__btn-container  js-lang-content-verify-de-menu \" >\n                <a  href=\"https:\/\/sii.pl\/en\/job-ads\/wroclaw\" class=\"nsw-a-button -ghost -blue nsw-o-slider__more-button \"   >\n        <span>Mehr dazu<\/span>\n    <\/a>\n            <\/div>\n                    <\/div>\n    <\/div>\n            <\/div>\n        <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":60521,"parent":0,"menu_order":15,"template":"","location":[3955],"class_list":["post-13533","branch","type-branch","status-publish","has-post-thumbnail","hentry","location-wroclaw-de"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sii.pl\/de\/wp-json\/wp\/v2\/branch\/13533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sii.pl\/de\/wp-json\/wp\/v2\/branch"}],"about":[{"href":"https:\/\/sii.pl\/de\/wp-json\/wp\/v2\/types\/branch"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sii.pl\/de\/wp-json\/wp\/v2\/media\/60521"}],"wp:attachment":[{"href":"https:\/\/sii.pl\/de\/wp-json\/wp\/v2\/media?parent=13533"}],"wp:term":[{"taxonomy":"location","embeddable":true,"href":"https:\/\/sii.pl\/de\/wp-json\/wp\/v2\/location?post=13533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}